{"id":1118,"date":"2025-04-20T09:27:51","date_gmt":"2025-04-20T09:27:51","guid":{"rendered":"https:\/\/chamrungroup.com\/saito\/?page_id=1118"},"modified":"2025-04-21T22:20:55","modified_gmt":"2025-04-21T22:20:55","slug":"admissions","status":"publish","type":"page","link":"https:\/\/chamrungroup.com\/saito\/admissions\/","title":{"rendered":"Admissions"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1118\" class=\"elementor elementor-1118\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f1dd73 e-flex e-con-boxed e-con e-parent\" data-id=\"3f1dd73\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15c73cd elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"15c73cd\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Admissions<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba5a15b elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"ba5a15b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tStart your learning journey with us today. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4b8e9a3 e-flex e-con-boxed e-con e-parent\" data-id=\"4b8e9a3\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-671b724 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"671b724\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Submit your  <span style=\"color:#cb1a38;\"> application <\/span> and we will reach out to you <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-150a351 e-con-full e-flex e-con e-child\" data-id=\"150a351\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-397d027 e-con-full e-flex e-con e-child\" data-id=\"397d027\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-484ede3 accordion-style elementor-widget elementor-widget-n-accordion\" data-id=\"484ede3\" data-element_type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-7580\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-7580\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Fill Admission Form <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-7580\" class=\"elementor-element elementor-element-18e6877 e-con-full e-flex e-con e-child\" data-id=\"18e6877\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6ea799c elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"6ea799c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Fill in the admission form before your preferred intake due date, via a downloadable form or directly online below. <a href=\"https:\/\/chamrungroup.com\/saito\/wp-content\/uploads\/2025\/04\/saito-uc-application-form-1_Compressed.pdf\">Get the downloadable form here<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-7581\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-7581\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Submit Supporting Documents <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-7581\" class=\"elementor-element elementor-element-342a6af e-con-full e-flex e-con e-child\" data-id=\"342a6af\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a9556c3 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"a9556c3\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tYou are required to submit the following documents to support your application.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26c73ba elementor-widget__width-inherit elementor-widget-tablet__width-initial elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"26c73ba\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-square\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M400 480H48c-26.51 0-48-21.49-48-48V80c0-26.51 21.49-48 48-48h352c26.51 0 48 21.49 48 48v352c0 26.51-21.49 48-48 48zm-204.686-98.059l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.248-16.379-6.249-22.628 0L184 302.745l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.25 16.379 6.25 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">For foreign students, two non-returnable passport-sized colour photographs \u2013 with white background.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-square\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M400 480H48c-26.51 0-48-21.49-48-48V80c0-26.51 21.49-48 48-48h352c26.51 0 48 21.49 48 48v352c0 26.51-21.49 48-48 48zm-204.686-98.059l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.248-16.379-6.249-22.628 0L184 302.745l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.25 16.379 6.25 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">For local students, a photocopy of your MyKad \u2013 front and back on one A4 Page in actual size.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-square\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M400 480H48c-26.51 0-48-21.49-48-48V80c0-26.51 21.49-48 48-48h352c26.51 0 48 21.49 48 48v352c0 26.51-21.49 48-48 48zm-204.686-98.059l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.248-16.379-6.249-22.628 0L184 302.745l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.25 16.379 6.25 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Certified true photocopies of education transcripts or academic results \u2013 SPM\/O-Levels\/STPM\/A-Levels\/Certificate\/Diploma or where applicable.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-square\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M400 480H48c-26.51 0-48-21.49-48-48V80c0-26.51 21.49-48 48-48h352c26.51 0 48 21.49 48 48v352c0 26.51-21.49 48-48 48zm-204.686-98.059l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.248-16.379-6.249-22.628 0L184 302.745l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.25 16.379 6.25 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Proof of English Level proficiency (if applicable).<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-square\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M400 480H48c-26.51 0-48-21.49-48-48V80c0-26.51 21.49-48 48-48h352c26.51 0 48 21.49 48 48v352c0 26.51-21.49 48-48 48zm-204.686-98.059l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.248-16.379-6.249-22.628 0L184 302.745l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.25 16.379 6.25 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">For credit transfers, certified true copies of relevant syllabus or course outline.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d161e5b elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"d161e5b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tPlease submit the required documents along with your application form if you\u2019re submitting the downloadable PDF form via email or in-person. For applications via the online form, you may submit the required documents after we reach out to you.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-7582\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-7582\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Pay Administration Fee <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-7582\" class=\"elementor-element elementor-element-2da9c4c e-con-full e-flex e-con e-child\" data-id=\"2da9c4c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-957619b elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"957619b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAll applicants would need to pay an administration fee of MYR100. Payments can be made by cheque, money order or bank transfer to Saito University College. After this step, we will reach out to you on any additional steps to complete your enrolment.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-382ac44 e-con-full e-flex e-con e-child\" data-id=\"382ac44\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-da69950 elementor-widget elementor-widget-image\" data-id=\"da69950\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"570\" src=\"https:\/\/chamrungroup.com\/saito\/wp-content\/uploads\/2025\/04\/admission-banner2.jpg\" class=\"attachment-large size-large wp-image-1123\" alt=\"\" srcset=\"https:\/\/chamrungroup.com\/saito\/wp-content\/uploads\/2025\/04\/admission-banner2.jpg 1000w, https:\/\/chamrungroup.com\/saito\/wp-content\/uploads\/2025\/04\/admission-banner2-300x214.jpg 300w, https:\/\/chamrungroup.com\/saito\/wp-content\/uploads\/2025\/04\/admission-banner2-768x547.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f6c723 e-flex e-con-boxed e-con e-parent\" data-id=\"5f6c723\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d58a597 e-con-full e-flex e-con e-child\" data-id=\"d58a597\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c9a3533 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"c9a3533\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Online Admission <span style=\"color:#cb1a38;\">Form  <\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7709131 e-con-full form-style e-flex e-con e-child\" data-id=\"7709131\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ee857e elementor-widget elementor-widget-wpforms\" data-id=\"4ee857e\" data-element_type=\"widget\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style id=\"wpforms-css-vars-root\">\n\t\t\t\t:root {\n\t\t\t\t\t--wpforms-field-border-radius: 3px;\n--wpforms-field-border-style: solid;\n--wpforms-field-border-size: 1px;\n--wpforms-field-background-color: #ffffff;\n--wpforms-field-border-color: rgba( 0, 0, 0, 0.25 );\n--wpforms-field-border-color-spare: rgba( 0, 0, 0, 0.25 );\n--wpforms-field-text-color: rgba( 0, 0, 0, 0.7 );\n--wpforms-field-menu-color: #ffffff;\n--wpforms-label-color: rgba( 0, 0, 0, 0.85 );\n--wpforms-label-sublabel-color: rgba( 0, 0, 0, 0.55 );\n--wpforms-label-error-color: #d63637;\n--wpforms-button-border-radius: 3px;\n--wpforms-button-border-style: none;\n--wpforms-button-border-size: 1px;\n--wpforms-button-background-color: #066aab;\n--wpforms-button-border-color: #066aab;\n--wpforms-button-text-color: #ffffff;\n--wpforms-page-break-color: #066aab;\n--wpforms-background-image: none;\n--wpforms-background-position: center center;\n--wpforms-background-repeat: no-repeat;\n--wpforms-background-size: cover;\n--wpforms-background-width: 100px;\n--wpforms-background-height: 100px;\n--wpforms-background-color: rgba( 0, 0, 0, 0 );\n--wpforms-background-url: none;\n--wpforms-container-padding: 0px;\n--wpforms-container-border-style: none;\n--wpforms-container-border-width: 1px;\n--wpforms-container-border-color: #000000;\n--wpforms-container-border-radius: 3px;\n--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\n\t\t\t\t}\n\t\t\t<\/style><style id=\"wpforms-css-vars-elementor-widget-4ee857e\">\n\t\t\t\t.elementor-widget-wpforms.elementor-element-4ee857e {\n\t\t\t\t\t--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n\n\t\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-1481\"><form id=\"wpforms-form-1481\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"1481\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/saito\/wp-json\/wp\/v2\/pages\/1118\" data-token=\"a194925e889b564f4f6e73745171b429\" data-token-time=\"1788337311\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-1481-field_1-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"1\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1481-field_2-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1481-field_2\" aria-hidden=\"false\">Level <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-1481-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>Level<\/option><option value=\"Degree\" >Degree<\/option><option value=\"Diploma\" >Diploma<\/option><option value=\"Foundation\" >Foundation<\/option><\/select><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1481-field_3-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"3\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1481-field_3\" aria-hidden=\"false\">Degree Programme Name<\/label><select id=\"wpforms-1481-field_3\" class=\"wpforms-field-medium\" name=\"wpforms[fields][3]\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>Degree Programme Name<\/option><option value=\"Bachelor of human resource management (hons)\" >Bachelor of human resource management (hons)<\/option><option value=\"Bachelor of business management (hons)\" >Bachelor of business management (hons)<\/option><option value=\"Bachelor of business (digital marketing) (hons)\" >Bachelor of business (digital marketing) (hons)<\/option><option value=\"Bachelor of arts in law enforcement (investigation) (hons)\" >Bachelor of arts in law enforcement (investigation) (hons)<\/option><option value=\"Bachelor of design (digital media) (hons)\" >Bachelor of design (digital media) (hons)<\/option><option value=\"Bachelor of design (graphic design) (hons)\" >Bachelor of design (graphic design) (hons)<\/option><option value=\"Bachelor of business in logistics management &amp; e-business (hons)\" >Bachelor of business in logistics management &amp; e-business (hons)<\/option><option value=\"Bachelor in hospitality management (hons)\" >Bachelor in hospitality management (hons)<\/option><\/select><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1481-field_4-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"4\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1481-field_4\" aria-hidden=\"false\">Diploma Programme Name<\/label><select id=\"wpforms-1481-field_4\" class=\"wpforms-field-medium\" name=\"wpforms[fields][4]\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>Diploma Programme Name<\/option><option value=\"Diploma in human resource management\" >Diploma in human resource management<\/option><option value=\"Diploma in business management\" >Diploma in business management<\/option><option value=\"Diploma in security management\" >Diploma in security management<\/option><option value=\"Diploma in law enforcement administration\" >Diploma in law enforcement administration<\/option><option value=\"Diploma in multimedia design\" >Diploma in multimedia design<\/option><option value=\"Diploma in graphic design\" >Diploma in graphic design<\/option><option value=\"Diploma in logistics management\" >Diploma in logistics management<\/option><option value=\"Diploma in hotel management\" >Diploma in hotel management<\/option><option value=\"Diploma in culinary arts\" >Diploma in culinary arts<\/option><option value=\"Diploma in pastry arts\" >Diploma in pastry arts<\/option><option value=\"Diploma in early childhood education\" >Diploma in early childhood education<\/option><\/select><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1481-field_5-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"5\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1481-field_5\" aria-hidden=\"false\">Foundation Programme Name<\/label><select id=\"wpforms-1481-field_5\" class=\"wpforms-field-medium\" name=\"wpforms[fields][5]\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>Foundation Programme Name<\/option><option value=\"Foundation in business\" >Foundation in business<\/option><option value=\"Foundation in design\" >Foundation in design<\/option><option value=\"Foundation in hospitality\" >Foundation in hospitality<\/option><option value=\"Foundation in business studies\" >Foundation in business studies<\/option><option value=\"Foundation in police science\" >Foundation in police science<\/option><\/select><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1481-field_6-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"6\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1481-field_6\" aria-hidden=\"false\">First Name  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-1481-field_6\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][6]\" placeholder=\"First Name \" aria-errormessage=\"wpforms-1481-field_6-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1481-field_7-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"7\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1481-field_7\" aria-hidden=\"false\">Last Name  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-1481-field_7\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][7]\" placeholder=\"Last Name \" aria-errormessage=\"wpforms-1481-field_7-error\" required><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1481-field_8-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"8\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1481-field_8\" aria-hidden=\"false\">Gender  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-1481-field_8\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][8]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>Gender <\/option><option value=\"Male\" >Male<\/option><option value=\"Female\" >Female<\/option><\/select><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1481-field_9-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"9\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1481-field_9\" aria-hidden=\"false\">NRIC  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-1481-field_9\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][9]\" placeholder=\"NRIC \" aria-errormessage=\"wpforms-1481-field_9-error\" required><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1481-field_10-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"10\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1481-field_10\" aria-hidden=\"false\">Email  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-1481-field_10\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][10]\" placeholder=\"Email \" spellcheck=\"false\" aria-errormessage=\"wpforms-1481-field_10-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1481-field_11-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"11\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1481-field_11\" aria-hidden=\"false\">Permanent Address<\/label><input type=\"text\" id=\"wpforms-1481-field_11\" class=\"wpforms-field-medium\" name=\"wpforms[fields][11]\" placeholder=\"Permanent Address\" aria-errormessage=\"wpforms-1481-field_11-error\" ><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1481-field_12-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"12\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1481-field_12\" aria-hidden=\"false\">Correspondence Address<\/label><input type=\"text\" id=\"wpforms-1481-field_12\" class=\"wpforms-field-medium\" name=\"wpforms[fields][12]\" placeholder=\"Correspondence Address\" aria-errormessage=\"wpforms-1481-field_12-error\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1481-field_13-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"13\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1481-field_13\" aria-hidden=\"false\">Phone <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-1481-field_13\" class=\"wpforms-field-medium wpforms-field-required wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][13]\" placeholder=\"Phone \" aria-label=\"Phone\" aria-errormessage=\"wpforms-1481-field_13-error\" required><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1481-field_14-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"14\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1481-field_14\" aria-hidden=\"false\">Parent or Guardian Name<\/label><input type=\"text\" id=\"wpforms-1481-field_14\" class=\"wpforms-field-medium\" name=\"wpforms[fields][14]\" placeholder=\"Parent or Guardian Name\" aria-errormessage=\"wpforms-1481-field_14-error\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1481-field_15-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"15\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1481-field_15\" aria-hidden=\"false\">Parent or Guardian Address<\/label><input type=\"text\" id=\"wpforms-1481-field_15\" class=\"wpforms-field-medium\" name=\"wpforms[fields][15]\" placeholder=\"Parent or Guardian Address\" aria-errormessage=\"wpforms-1481-field_15-error\" ><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1481-field_17-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"17\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1481-field_17\" aria-hidden=\"false\">Parent or Guardian Phone<\/label><input type=\"tel\" id=\"wpforms-1481-field_17\" class=\"wpforms-field-medium wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][17]\" placeholder=\"Parent or Guardian Phone\" aria-label=\"Parent or Guardian Phone\" aria-errormessage=\"wpforms-1481-field_17-error\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1481-field_18-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"18\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1481-field_18\" aria-hidden=\"false\">Name of Institution \/ School<\/label><input type=\"text\" id=\"wpforms-1481-field_18\" class=\"wpforms-field-medium\" name=\"wpforms[fields][18]\" placeholder=\"Name of Institution \/ School\" aria-errormessage=\"wpforms-1481-field_18-error\" ><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1481-field_20-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"20\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1481-field_20\" aria-hidden=\"false\">Name of Qualification<\/label><select id=\"wpforms-1481-field_20\" class=\"wpforms-field-medium\" name=\"wpforms[fields][20]\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>Name of Qualification<\/option><option value=\"PT3\" >PT3<\/option><option value=\"SPM\" >SPM<\/option><option value=\"STPM\" >STPM<\/option><option value=\"UEC\" >UEC<\/option><option value=\"O&#039;Level\" >O&#039;Level<\/option><option value=\"A&#039;Level\" >A&#039;Level<\/option><\/select><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1481-field_21-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"21\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1481-field_21\" aria-hidden=\"false\">Other Qualifications<\/label><input type=\"text\" id=\"wpforms-1481-field_21\" class=\"wpforms-field-medium\" name=\"wpforms[fields][21]\" placeholder=\"Other Qualifications\" aria-errormessage=\"wpforms-1481-field_21-error\" ><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-1481-field_22-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"22\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-100\"><div id=\"wpforms-1481-field_23-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"23\"><fieldset><legend class=\"wpforms-field-label\">English Language Proficiency Requirement<\/legend><ul id=\"wpforms-1481-field_23\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-1481-field_23_1\" name=\"wpforms[fields][23][]\" value=\"TOEFL\" aria-errormessage=\"wpforms-1481-field_23_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1481-field_23_1\">TOEFL<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-1481-field_23_2\" name=\"wpforms[fields][23][]\" value=\"IELTS\" aria-errormessage=\"wpforms-1481-field_23_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1481-field_23_2\">IELTS<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-1481-field_23_3\" name=\"wpforms[fields][23][]\" value=\"TOIEC\" aria-errormessage=\"wpforms-1481-field_23_3-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1481-field_23_3\">TOIEC<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-1481-field_23_4\" name=\"wpforms[fields][23][]\" value=\"MUET\" aria-errormessage=\"wpforms-1481-field_23_4-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1481-field_23_4\">MUET<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-1481-field_23_5\" name=\"wpforms[fields][23][]\" value=\"1119\" aria-errormessage=\"wpforms-1481-field_23_5-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1481-field_23_5\">1119<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-1481-field_23_6\" name=\"wpforms[fields][23][]\" value=\"SPM English\" aria-errormessage=\"wpforms-1481-field_23_6-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1481-field_23_6\">SPM English<\/label><\/li><\/ul><\/fieldset><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-100\"><div id=\"wpforms-1481-field_24-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"24\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1481-field_24\" aria-hidden=\"false\">Others<\/label><input type=\"text\" id=\"wpforms-1481-field_24\" class=\"wpforms-field-large\" name=\"wpforms[fields][24]\" placeholder=\"Others\" aria-errormessage=\"wpforms-1481-field_24-error\" ><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-100\"><div id=\"wpforms-1481-field_27-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-inline\" data-field-id=\"27\"><fieldset><legend class=\"wpforms-field-label\">Do you have any disability, impairment or long term medical condition, which may affect your studies  (copy) <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-1481-field_27\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-1481-field_27_1\" name=\"wpforms[fields][27]\" value=\"No\" aria-errormessage=\"wpforms-1481-field_27_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1481-field_27_1\">No<\/label><\/li><li class=\"choice-2 depth-1 wpforms-selected\"><input type=\"radio\" id=\"wpforms-1481-field_27_2\" name=\"wpforms[fields][27]\" value=\"Yes\" aria-errormessage=\"wpforms-1481-field_27_2-error\" required  checked='checked'><label class=\"wpforms-field-label-inline\" for=\"wpforms-1481-field_27_2\">Yes<\/label><\/li><\/ul><\/fieldset><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-100\"><div id=\"wpforms-1481-field_26-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"26\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1481-field_26\" aria-hidden=\"false\">If yes, please specify with the medical report<\/label><input type=\"text\" id=\"wpforms-1481-field_26\" class=\"wpforms-field-large\" name=\"wpforms[fields][26]\" placeholder=\"If yes, please specify with the medical report\" aria-errormessage=\"wpforms-1481-field_26-error\" ><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-100\"><div id=\"wpforms-1481-field_25-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-inline\" data-field-id=\"25\"><fieldset><legend class=\"wpforms-field-label\">Do you have any Saito Counsellor  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-1481-field_25\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-1481-field_25_1\" name=\"wpforms[fields][25]\" value=\"No\" aria-errormessage=\"wpforms-1481-field_25_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1481-field_25_1\">No<\/label><\/li><li class=\"choice-2 depth-1 wpforms-selected\"><input type=\"radio\" id=\"wpforms-1481-field_25_2\" name=\"wpforms[fields][25]\" value=\"Yes\" aria-errormessage=\"wpforms-1481-field_25_2-error\" required  checked='checked'><label class=\"wpforms-field-label-inline\" for=\"wpforms-1481-field_25_2\">Yes<\/label><\/li><\/ul><\/fieldset><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-100\"><div id=\"wpforms-1481-field_28-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"28\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1481-field_28\" aria-hidden=\"false\">Can you provide your Saito Counsellor&#039;s name?<\/label><input type=\"text\" id=\"wpforms-1481-field_28\" class=\"wpforms-field-large\" name=\"wpforms[fields][28]\" placeholder=\"Can you provide your Saito Counsellor&#039;s name?\" aria-errormessage=\"wpforms-1481-field_28-error\" ><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-100\"><div id=\"wpforms-1481-field_29-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-inline\" data-field-id=\"29\"><fieldset><legend class=\"wpforms-field-label\">How did you find us?  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-1481-field_29\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-1481-field_29_1\" name=\"wpforms[fields][29]\" value=\"Google \/ Search Engine\" aria-errormessage=\"wpforms-1481-field_29_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1481-field_29_1\">Google \/ Search Engine<\/label><\/li><li class=\"choice-2 depth-1 wpforms-selected\"><input type=\"radio\" id=\"wpforms-1481-field_29_2\" name=\"wpforms[fields][29]\" value=\"Social Media\" aria-errormessage=\"wpforms-1481-field_29_2-error\" required  checked='checked'><label class=\"wpforms-field-label-inline\" for=\"wpforms-1481-field_29_2\">Social Media<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-1481-field_29_4\" name=\"wpforms[fields][29]\" value=\"Roadshow \/ Event \/ Education Fair\" aria-errormessage=\"wpforms-1481-field_29_4-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1481-field_29_4\">Roadshow \/ Event \/ Education Fair<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-1481-field_29_5\" name=\"wpforms[fields][29]\" value=\"SGS \/ Friend\" aria-errormessage=\"wpforms-1481-field_29_5-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1481-field_29_5\">SGS \/ Friend<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"radio\" id=\"wpforms-1481-field_29_6\" name=\"wpforms[fields][29]\" value=\"Others\" aria-errormessage=\"wpforms-1481-field_29_6-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1481-field_29_6\">Others<\/label><\/li><\/ul><\/fieldset><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-100\"><div id=\"wpforms-1481-field_30-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"30\"><fieldset><legend class=\"wpforms-field-label\">Acknowledgement  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-1481-field_30\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-1481-field_30_1\" name=\"wpforms[fields][30][]\" value=\"By submitting this form, you hereby agree to PDPA 2010 that Saito University College may collect, obtain, store and process your personal data that you provide in this form for the purpose of receiving updates, news, promotional and marketing mails or materials from Saito University College.\" aria-errormessage=\"wpforms-1481-field_30_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1481-field_30_1\">By submitting this form, you hereby agree to PDPA 2010 that Saito University College may collect, obtain, store and process your personal data that you provide in this form for the purpose of receiving updates, news, promotional and marketing mails or materials from Saito University College.<\/label><\/li><\/ul><\/fieldset><\/div><\/div><\/div><\/div><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"1481\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/chamrungroup.com\/saito\/wp-json\/wp\/v2\/pages\/1118\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-1481\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img decoding=\"async\" src=\"https:\/\/chamrungroup.com\/saito\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4dbaa91 e-flex e-con-boxed e-con e-parent\" data-id=\"4dbaa91\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a381c22 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a381c22\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">further questions?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3bfb10 elementor-invisible elementor-widget elementor-widget-button\" data-id=\"d3bfb10\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/chamrungroup.com\/saito\/contact-us\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ask Now<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Admissions Start your learning journey with us today. Submit your application and we will reach out to you Fill Admission Form Fill in the admission form before your preferred intake due date, via a downloadable form or directly online below. Get the downloadable form here. Submit Supporting Documents You are required to submit the following [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1118","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/chamrungroup.com\/saito\/wp-json\/wp\/v2\/pages\/1118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chamrungroup.com\/saito\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/chamrungroup.com\/saito\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/chamrungroup.com\/saito\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chamrungroup.com\/saito\/wp-json\/wp\/v2\/comments?post=1118"}],"version-history":[{"count":28,"href":"https:\/\/chamrungroup.com\/saito\/wp-json\/wp\/v2\/pages\/1118\/revisions"}],"predecessor-version":[{"id":1761,"href":"https:\/\/chamrungroup.com\/saito\/wp-json\/wp\/v2\/pages\/1118\/revisions\/1761"}],"wp:attachment":[{"href":"https:\/\/chamrungroup.com\/saito\/wp-json\/wp\/v2\/media?parent=1118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}