{"id":2028,"date":"2025-04-09T08:28:22","date_gmt":"2025-04-09T08:28:22","guid":{"rendered":"https:\/\/chamrungroup.com\/mdis\/?page_id=2028"},"modified":"2025-04-09T21:27:17","modified_gmt":"2025-04-09T21:27:17","slug":"hostel-enquiry","status":"publish","type":"page","link":"https:\/\/chamrungroup.com\/mdis\/hostel-enquiry\/","title":{"rendered":"Hostel Enquiry"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2028\" class=\"elementor elementor-2028\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-af2a526 e-flex e-con-boxed e-con e-parent\" data-id=\"af2a526\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-88ba947 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"88ba947\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HOSTEL ENQUIRY<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f77b48b e-flex e-con-boxed e-con e-parent\" data-id=\"f77b48b\" data-element_type=\"container\" id=\"Campus-Experience\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-fba3b8b e-con-full e-flex e-con e-child\" data-id=\"fba3b8b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ffcda6 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3ffcda6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"color:#cb1a38;\">Enquiry<\/span> form<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f1b755 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"6f1b755\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Please fill in the enquiry form if you\u2019re interested in renting a hostel room\/suite, we will respond to your inquiry as soon as possible.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-56b45b2 e-con-full e-flex e-con e-child\" data-id=\"56b45b2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c08ee2c elementor-widget elementor-widget-wpforms\" data-id=\"c08ee2c\" data-element_type=\"widget\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style id=\"wpforms-css-vars-root\">\n\t\t\t\t:root {\n\t\t\t\t\t--wpforms-field-border-radius: 3px;\n--wpforms-field-border-style: solid;\n--wpforms-field-border-size: 1px;\n--wpforms-field-background-color: #ffffff;\n--wpforms-field-border-color: rgba( 0, 0, 0, 0.25 );\n--wpforms-field-border-color-spare: rgba( 0, 0, 0, 0.25 );\n--wpforms-field-text-color: rgba( 0, 0, 0, 0.7 );\n--wpforms-field-menu-color: #ffffff;\n--wpforms-label-color: rgba( 0, 0, 0, 0.85 );\n--wpforms-label-sublabel-color: rgba( 0, 0, 0, 0.55 );\n--wpforms-label-error-color: #d63637;\n--wpforms-button-border-radius: 3px;\n--wpforms-button-border-style: none;\n--wpforms-button-border-size: 1px;\n--wpforms-button-background-color: #066aab;\n--wpforms-button-border-color: #066aab;\n--wpforms-button-text-color: #ffffff;\n--wpforms-page-break-color: #066aab;\n--wpforms-background-image: none;\n--wpforms-background-position: center center;\n--wpforms-background-repeat: no-repeat;\n--wpforms-background-size: cover;\n--wpforms-background-width: 100px;\n--wpforms-background-height: 100px;\n--wpforms-background-color: rgba( 0, 0, 0, 0 );\n--wpforms-background-url: none;\n--wpforms-container-padding: 0px;\n--wpforms-container-border-style: none;\n--wpforms-container-border-width: 1px;\n--wpforms-container-border-color: #000000;\n--wpforms-container-border-radius: 3px;\n--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\n\t\t\t\t}\n\t\t\t<\/style><style id=\"wpforms-css-vars-elementor-widget-c08ee2c\">\n\t\t\t\t.elementor-widget-wpforms.elementor-element-c08ee2c {\n\t\t\t\t\t--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n\n\t\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-1921\"><form id=\"wpforms-form-1921\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"1921\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/mdis\/wp-json\/wp\/v2\/pages\/2028\" data-token=\"34a1b97fd28cb4c78a021830f5e81368\" data-token-time=\"1788312684\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-1921-field_1-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"1\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1921-field_2-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1921-field_2\" aria-hidden=\"false\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-1921-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" placeholder=\"Name\" aria-errormessage=\"wpforms-1921-field_2-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1921-field_3-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"3\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1921-field_3\" aria-hidden=\"false\">Mobile <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-1921-field_3\" class=\"wpforms-field-medium wpforms-field-required wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][3]\" placeholder=\"Mobile\" aria-label=\"Mobile\" aria-errormessage=\"wpforms-1921-field_3-error\" required><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1921-field_4-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"4\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1921-field_4\" aria-hidden=\"false\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-1921-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" placeholder=\"Email\" spellcheck=\"false\" aria-errormessage=\"wpforms-1921-field_4-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-1921-field_5-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"5\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1921-field_5\" aria-hidden=\"false\">You are a\/an <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-1921-field_5\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][5]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>You are a\/an<\/option><option value=\"Local Student\" >Local Student<\/option><option value=\"International Student\" >International Student<\/option><\/select><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-1921-field_7-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"7\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1921-field_7\" aria-hidden=\"false\">Message <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-1921-field_7\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][7]\" placeholder=\"Message\" aria-errormessage=\"wpforms-1921-field_7-error\" required><\/textarea><\/div><div id=\"wpforms-1921-field_8-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"8\"><fieldset><legend class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">Checkboxes <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-1921-field_8\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-1921-field_8_1\" name=\"wpforms[fields][8][]\" value=\"MDIS Malaysia International College is committed to maintaining the confidentiality of the student\u2019s personal information and undertakes not to divulge any of the students\u2019 personal information to any third party without the consent of the student.\" aria-errormessage=\"wpforms-1921-field_8_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1921-field_8_1\">MDIS Malaysia International College is committed to maintaining the confidentiality of the student\u2019s personal information and undertakes not to divulge any of the students\u2019 personal information to any third party without the consent of the student.<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-1921-field_6-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"6\"><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"1921\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/chamrungroup.com\/mdis\/wp-json\/wp\/v2\/pages\/2028\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-1921\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img decoding=\"async\" src=\"https:\/\/chamrungroup.com\/mdis\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>HOSTEL ENQUIRY Enquiry form Please fill in the enquiry form if you\u2019re interested in renting a hostel room\/suite, we will respond to your inquiry as soon as possible. Please enable JavaScript in your browser to complete this form.Please enable JavaScript in your browser to complete this form.Name *Mobile *Email *You are a\/an *You are a\/anLocal [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2028","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/chamrungroup.com\/mdis\/wp-json\/wp\/v2\/pages\/2028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chamrungroup.com\/mdis\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/chamrungroup.com\/mdis\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/chamrungroup.com\/mdis\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chamrungroup.com\/mdis\/wp-json\/wp\/v2\/comments?post=2028"}],"version-history":[{"count":7,"href":"https:\/\/chamrungroup.com\/mdis\/wp-json\/wp\/v2\/pages\/2028\/revisions"}],"predecessor-version":[{"id":2422,"href":"https:\/\/chamrungroup.com\/mdis\/wp-json\/wp\/v2\/pages\/2028\/revisions\/2422"}],"wp:attachment":[{"href":"https:\/\/chamrungroup.com\/mdis\/wp-json\/wp\/v2\/media?parent=2028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}